  {"id":9008,"count":2,"description":"","link":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/","name":"Steven R. Chicurel","slug":"steven-r-chicurel","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Steven R. Chicurel Archives | University of Central Florida News<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steven R. Chicurel Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/\" \/>\n<meta property=\"og:site_name\" content=\"University of Central Florida News | UCF Today\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UCF\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/steven-r-chicurel\\\/\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/steven-r-chicurel\\\/\",\"name\":\"Steven R. Chicurel Archives | University of Central Florida News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/steven-r-chicurel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/steven-r-chicurel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steven R. Chicurel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/\",\"name\":\"University of Central Florida News | UCF Today\",\"description\":\"Central Florida Research, Arts, Technology, Student Life and College News, Stories and More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/news\\\/tag\\\/steven-r-chicurel\\\/#local-main-organization-logo\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"University of Central Florida\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Steven R. Chicurel Archives | University of Central Florida News","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Steven R. Chicurel Archives","og_url":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/","og_site_name":"University of Central Florida News | UCF Today","twitter_card":"summary_large_image","twitter_site":"@UCF","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/","url":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/","name":"Steven R. Chicurel Archives | University of Central Florida News","isPartOf":{"@id":"https:\/\/www.ucf.edu\/news\/#website"},"breadcrumb":{"@id":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ucf.edu\/news\/"},{"@type":"ListItem","position":2,"name":"Steven R. Chicurel"}]},{"@type":"WebSite","@id":"https:\/\/www.ucf.edu\/news\/#website","url":"https:\/\/www.ucf.edu\/news\/","name":"University of Central Florida News | UCF Today","description":"Central Florida Research, Arts, Technology, Student Life and College News, Stories and More","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucf.edu\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ucf.edu\/news\/tag\/steven-r-chicurel\/#local-main-organization-logo","url":"","contentUrl":"","caption":"University of Central Florida"}]}},"_links":{"self":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/tags\/9008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/posts?tags=9008"},{"href":"https:\/\/www.ucf.edu\/news\/wp-json\/wp\/v2\/statements?tags=9008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}